{"id":4907,"date":"2025-10-10T12:10:30","date_gmt":"2025-10-10T02:10:30","guid":{"rendered":"\/eu-uk\/?p=4907"},"modified":"2025-10-10T12:13:42","modified_gmt":"2025-10-10T02:13:42","slug":"quarterly-report-period-ended-30-september-2025","status":"publish","type":"post","link":"\/eu-uk\/blog\/2025\/10\/10\/quarterly-report-period-ended-30-september-2025\/","title":{"rendered":"Quarterly Report \u2013 period ended 30 September 2025"},"content":{"rendered":"<p><span data-contrast=\"auto\">Orthocell has today released its Quarterly Report for the period ended 30 September 2025, outlining a period of continued growth and strong commercial progress.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Key highlights for the quarter include:<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<ul>\n<li><span data-contrast=\"auto\">Record revenue for the quarter of $3.0 million driven primarily by Remplir\u2019s growing market penetration in Australia and Singapore\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\">Orthocell maintains robust cash reserves of $27 million in cash as at 30 September 2025 and is well-positioned for continued commercial expansion<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\">Remplir rollout in the US$1.6 Billion US market ahead of schedule, with Distribution networks now spanning 25 states and reaching 40% of the US population, and first surgeries complete\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\">First distributor appointed for Remplir in US$75 million Canadian market, with first sales targeted for December 2025 Quarter<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\">Remplir used in nerve-sparing prostate cancer surgery\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\">Remplir study results deliver compelling 81% success rate<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\">Strengthened leadership with Executive and Board appointments<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<\/ul>\n<p><span data-ccp-props=\"{}\">\u00a0<\/span><span data-contrast=\"auto\">Orthocell CEO and MD, Paul Anderson, said:\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u201cWe have continued to build strong commercial momentum in the September quarter with another record quarter of sales revenue delivered primarily from Remplir sales in our existing markets in Australia and Singapore.\u201d<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/cdn-api.markitdigital.com\/apiman-gateway\/ASX\/asx-research\/1.0\/file\/2924-03006103-6A1289395&amp;v=undefined\"><span data-contrast=\"auto\">Click to read the ASX release.<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Orthocell has today released its Quarterly Report for the period ended 30 September 2025, outlining a period of continued growth and strong commercial progress.<\/p>\n","protected":false},"author":2,"featured_media":4909,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1],"tags":[],"class_list":["post-4907","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-video"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Orthocell has today released its Quarterly Report for the period ended 30 September 2025, outlining a period of continued growth and strong commercial progress.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Orthocell\"\/>\n\t<link rel=\"canonical\" href=\"\/eu-uk\/blog\/2025\/10\/10\/quarterly-report-period-ended-30-september-2025\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_GB\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Orthocell EU\/UK -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Quarterly Report \u2013 period ended 30 September 2025 - Orthocell EU\/UK\" \/>\n\t\t<meta property=\"og:description\" content=\"Orthocell has today released its Quarterly Report for the period ended 30 September 2025, outlining a period of continued growth and strong commercial progress.\" \/>\n\t\t<meta property=\"og:url\" content=\"\/eu-uk\/blog\/2025\/10\/10\/quarterly-report-period-ended-30-september-2025\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-10-10T02:10:30+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-10-10T02:13:42+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Quarterly Report \u2013 period ended 30 September 2025 - Orthocell EU\/UK\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Orthocell has today released its Quarterly Report for the period ended 30 September 2025, outlining a period of continued growth and strong commercial progress.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\\\/blog\\\/2025\\\/10\\\/10\\\/quarterly-report-period-ended-30-september-2025\\\/#blogposting\",\"name\":\"Quarterly Report \\u2013 period ended 30 September 2025 - Orthocell EU\\\/UK\",\"headline\":\"Quarterly Report \\u2013 period ended 30 September 2025\",\"author\":{\"@id\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\\\/blog\\\/author\\\/hcartres\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/10\\\/60.png\",\"width\":2000,\"height\":1429},\"datePublished\":\"2025-10-10T12:10:30+10:00\",\"dateModified\":\"2025-10-10T12:13:42+10:00\",\"inLanguage\":\"en-GB\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\\\/blog\\\/2025\\\/10\\\/10\\\/quarterly-report-period-ended-30-september-2025\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\\\/blog\\\/2025\\\/10\\\/10\\\/quarterly-report-period-ended-30-september-2025\\\/#webpage\"},\"articleSection\":\"Video\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\\\/blog\\\/2025\\\/10\\\/10\\\/quarterly-report-period-ended-30-september-2025\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/orthocell.com\\\/eu-uk#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\\\/blog\\\/category\\\/video\\\/#listItem\",\"name\":\"Video\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\\\/blog\\\/category\\\/video\\\/#listItem\",\"position\":2,\"name\":\"Video\",\"item\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\\\/blog\\\/category\\\/video\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\\\/blog\\\/2025\\\/10\\\/10\\\/quarterly-report-period-ended-30-september-2025\\\/#listItem\",\"name\":\"Quarterly Report \\u2013 period ended 30 September 2025\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/orthocell.com\\\/eu-uk#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\\\/blog\\\/2025\\\/10\\\/10\\\/quarterly-report-period-ended-30-september-2025\\\/#listItem\",\"position\":3,\"name\":\"Quarterly Report \\u2013 period ended 30 September 2025\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\\\/blog\\\/category\\\/video\\\/#listItem\",\"name\":\"Video\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\\\/#organization\",\"name\":\"Orthocell EU\\\/UK\",\"url\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\\\/blog\\\/author\\\/hcartres\\\/#author\",\"url\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\\\/blog\\\/author\\\/hcartres\\\/\",\"name\":\"Orthocell\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\\\/blog\\\/2025\\\/10\\\/10\\\/quarterly-report-period-ended-30-september-2025\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0aab809366bb46167bf34d1c56223f53c568b96a5870f19d01139e3e4a20c2f1?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Orthocell\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\\\/blog\\\/2025\\\/10\\\/10\\\/quarterly-report-period-ended-30-september-2025\\\/#webpage\",\"url\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\\\/blog\\\/2025\\\/10\\\/10\\\/quarterly-report-period-ended-30-september-2025\\\/\",\"name\":\"Quarterly Report \\u2013 period ended 30 September 2025 - Orthocell EU\\\/UK\",\"description\":\"Orthocell has today released its Quarterly Report for the period ended 30 September 2025, outlining a period of continued growth and strong commercial progress.\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\\\/blog\\\/2025\\\/10\\\/10\\\/quarterly-report-period-ended-30-september-2025\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\\\/blog\\\/author\\\/hcartres\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\\\/blog\\\/author\\\/hcartres\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/10\\\/60.png\",\"@id\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\\\/blog\\\/2025\\\/10\\\/10\\\/quarterly-report-period-ended-30-september-2025\\\/#mainImage\",\"width\":2000,\"height\":1429},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\\\/blog\\\/2025\\\/10\\\/10\\\/quarterly-report-period-ended-30-september-2025\\\/#mainImage\"},\"datePublished\":\"2025-10-10T12:10:30+10:00\",\"dateModified\":\"2025-10-10T12:13:42+10:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\\\/#website\",\"url\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\\\/\",\"name\":\"Orthocell EU\\\/UK\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/orthocell.com\\\/eu-uk\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Quarterly Report \u2013 period ended 30 September 2025 - Orthocell EU\/UK","description":"Orthocell has today released its Quarterly Report for the period ended 30 September 2025, outlining a period of continued growth and strong commercial progress.","canonical_url":"\/eu-uk\/blog\/2025\/10\/10\/quarterly-report-period-ended-30-september-2025\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"\/eu-uk\/blog\/2025\/10\/10\/quarterly-report-period-ended-30-september-2025\/#blogposting","name":"Quarterly Report \u2013 period ended 30 September 2025 - Orthocell EU\/UK","headline":"Quarterly Report \u2013 period ended 30 September 2025","author":{"@id":"\/eu-uk\/blog\/author\/hcartres\/#author"},"publisher":{"@id":"\/eu-uk\/#organization"},"image":{"@type":"ImageObject","url":"\/eu-uk\/wp-content\/uploads\/sites\/6\/2025\/10\/60.png","width":2000,"height":1429},"datePublished":"2025-10-10T12:10:30+10:00","dateModified":"2025-10-10T12:13:42+10:00","inLanguage":"en-GB","mainEntityOfPage":{"@id":"\/eu-uk\/blog\/2025\/10\/10\/quarterly-report-period-ended-30-september-2025\/#webpage"},"isPartOf":{"@id":"\/eu-uk\/blog\/2025\/10\/10\/quarterly-report-period-ended-30-september-2025\/#webpage"},"articleSection":"Video"},{"@type":"BreadcrumbList","@id":"\/eu-uk\/blog\/2025\/10\/10\/quarterly-report-period-ended-30-september-2025\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/orthocell.com\/eu-uk#listItem","position":1,"name":"Home","item":"https:\/\/orthocell.com\/eu-uk","nextItem":{"@type":"ListItem","@id":"\/eu-uk\/blog\/category\/video\/#listItem","name":"Video"}},{"@type":"ListItem","@id":"\/eu-uk\/blog\/category\/video\/#listItem","position":2,"name":"Video","item":"\/eu-uk\/blog\/category\/video\/","nextItem":{"@type":"ListItem","@id":"\/eu-uk\/blog\/2025\/10\/10\/quarterly-report-period-ended-30-september-2025\/#listItem","name":"Quarterly Report \u2013 period ended 30 September 2025"},"previousItem":{"@type":"ListItem","@id":"https:\/\/orthocell.com\/eu-uk#listItem","name":"Home"}},{"@type":"ListItem","@id":"\/eu-uk\/blog\/2025\/10\/10\/quarterly-report-period-ended-30-september-2025\/#listItem","position":3,"name":"Quarterly Report \u2013 period ended 30 September 2025","previousItem":{"@type":"ListItem","@id":"\/eu-uk\/blog\/category\/video\/#listItem","name":"Video"}}]},{"@type":"Organization","@id":"\/eu-uk\/#organization","name":"Orthocell EU\/UK","url":"\/eu-uk\/"},{"@type":"Person","@id":"\/eu-uk\/blog\/author\/hcartres\/#author","url":"\/eu-uk\/blog\/author\/hcartres\/","name":"Orthocell","image":{"@type":"ImageObject","@id":"\/eu-uk\/blog\/2025\/10\/10\/quarterly-report-period-ended-30-september-2025\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/0aab809366bb46167bf34d1c56223f53c568b96a5870f19d01139e3e4a20c2f1?s=96&d=mm&r=g","width":96,"height":96,"caption":"Orthocell"}},{"@type":"WebPage","@id":"\/eu-uk\/blog\/2025\/10\/10\/quarterly-report-period-ended-30-september-2025\/#webpage","url":"\/eu-uk\/blog\/2025\/10\/10\/quarterly-report-period-ended-30-september-2025\/","name":"Quarterly Report \u2013 period ended 30 September 2025 - Orthocell EU\/UK","description":"Orthocell has today released its Quarterly Report for the period ended 30 September 2025, outlining a period of continued growth and strong commercial progress.","inLanguage":"en-GB","isPartOf":{"@id":"\/eu-uk\/#website"},"breadcrumb":{"@id":"\/eu-uk\/blog\/2025\/10\/10\/quarterly-report-period-ended-30-september-2025\/#breadcrumblist"},"author":{"@id":"\/eu-uk\/blog\/author\/hcartres\/#author"},"creator":{"@id":"\/eu-uk\/blog\/author\/hcartres\/#author"},"image":{"@type":"ImageObject","url":"\/eu-uk\/wp-content\/uploads\/sites\/6\/2025\/10\/60.png","@id":"\/eu-uk\/blog\/2025\/10\/10\/quarterly-report-period-ended-30-september-2025\/#mainImage","width":2000,"height":1429},"primaryImageOfPage":{"@id":"\/eu-uk\/blog\/2025\/10\/10\/quarterly-report-period-ended-30-september-2025\/#mainImage"},"datePublished":"2025-10-10T12:10:30+10:00","dateModified":"2025-10-10T12:13:42+10:00"},{"@type":"WebSite","@id":"\/eu-uk\/#website","url":"\/eu-uk\/","name":"Orthocell EU\/UK","inLanguage":"en-GB","publisher":{"@id":"\/eu-uk\/#organization"}}]},"og:locale":"en_GB","og:site_name":"Orthocell EU\/UK -","og:type":"article","og:title":"Quarterly Report \u2013 period ended 30 September 2025 - Orthocell EU\/UK","og:description":"Orthocell has today released its Quarterly Report for the period ended 30 September 2025, outlining a period of continued growth and strong commercial progress.","og:url":"\/eu-uk\/blog\/2025\/10\/10\/quarterly-report-period-ended-30-september-2025\/","article:published_time":"2025-10-10T02:10:30+00:00","article:modified_time":"2025-10-10T02:13:42+00:00","twitter:card":"summary_large_image","twitter:title":"Quarterly Report \u2013 period ended 30 September 2025 - Orthocell EU\/UK","twitter:description":"Orthocell has today released its Quarterly Report for the period ended 30 September 2025, outlining a period of continued growth and strong commercial progress."},"aioseo_meta_data":[],"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/orthocell.com\/eu-uk\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"\/eu-uk\/blog\/category\/video\/\" title=\"Video\">Video<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tQuarterly Report \u2013 period ended 30 September 2025\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/orthocell.com\/eu-uk"},{"label":"Video","link":"\/eu-uk\/blog\/category\/video\/"},{"label":"Quarterly Report \u2013 period ended 30 September 2025","link":"\/eu-uk\/blog\/2025\/10\/10\/quarterly-report-period-ended-30-september-2025\/"}],"_links":{"self":[{"href":"\/eu-uk\/wp-json\/wp\/v2\/posts\/4907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"\/eu-uk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/eu-uk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/eu-uk\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"\/eu-uk\/wp-json\/wp\/v2\/comments?post=4907"}],"version-history":[{"count":1,"href":"\/eu-uk\/wp-json\/wp\/v2\/posts\/4907\/revisions"}],"predecessor-version":[{"id":4910,"href":"\/eu-uk\/wp-json\/wp\/v2\/posts\/4907\/revisions\/4910"}],"wp:featuredmedia":[{"embeddable":true,"href":"\/eu-uk\/wp-json\/wp\/v2\/media\/4909"}],"wp:attachment":[{"href":"\/eu-uk\/wp-json\/wp\/v2\/media?parent=4907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/eu-uk\/wp-json\/wp\/v2\/categories?post=4907"},{"taxonomy":"post_tag","embeddable":true,"href":"\/eu-uk\/wp-json\/wp\/v2\/tags?post=4907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}